{"id":189,"date":"2012-07-18T15:57:20","date_gmt":"2012-07-18T18:57:20","guid":{"rendered":"http:\/\/mprinformatica.com.br\/blog\/?p=189"},"modified":"2012-07-18T15:57:20","modified_gmt":"2012-07-18T18:57:20","slug":"o-que-e-rgb","status":"publish","type":"post","link":"https:\/\/www.mprinformatica.com.br\/blog\/2012\/07\/18\/o-que-e-rgb\/","title":{"rendered":"O que \u00e9 RGB ?"},"content":{"rendered":"<p><strong>RGB <\/strong>\u00e9 a sigla do sistema de cores aditivas formado pelas iniciais das cores em ingl\u00eas Red, Green e Blue, que significa em portugu\u00eas, respectivamente, Vermelho, Verde e Azul.<\/p>\n<p><a href=\"http:\/\/www.mprinformatica.com.br\/blog\/wp-content\/uploads\/2012\/07\/200px-AdditiveColor.svg_.png\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.mprinformatica.com.br\/blog\/wp-content\/uploads\/2012\/07\/200px-AdditiveColor.svg_.png\" alt=\"\" title=\"200px-AdditiveColor.svg\" width=\"200\" height=\"200\" class=\"aligncenter size-full wp-image-190\" \/><\/a><\/p>\n<p>O sistema de cores luminosas RGB (tamb\u00e9m designado por cor-luz) \u00e9 usado nos objetos que emitem luz como, por exemplo, os monitores de computador e televis\u00e3o, as c\u00e2meras digitais, o scanner, entre outros.<\/p>\n<p>J\u00e1 nas impressoras \u00e9 utilizado o padr\u00e3o de cores subtrativas denominado CMYK, formado pelos pigmentos prim\u00e1rios Cyan (Ciano), Magenta (Magenta) e Yellow (Amarelo) e ainda, o blacK (Preto).<\/p>\n<p>As cores s\u00e3o obtidas atrav\u00e9s das misturas das tr\u00eas cores prim\u00e1rias, em quantidades determinadas. Cada uma das cores obtidas est\u00e3o enquadradas numa escala que varia de 0 a 255. Quando a mistura das tr\u00eas cores est\u00e1 no valor m\u00ednimo (0, 0, 0), o resultado \u00e9 a cor preta. Quanto est\u00e1 no m\u00e1ximo (255, 255, 255), resulta na cor branca.<\/p>\n<p>A varia\u00e7\u00e3o entre valores m\u00ednimos corresponde a tons escuros e entre os valores m\u00e1ximos, os tons s\u00e3o mais intensos, mais claros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RGB \u00e9 a sigla do sistema de cores aditivas formado pelas iniciais das cores em ingl\u00eas Red, Green e Blue, que significa em portugu\u00eas, respectivamente, Vermelho, Verde e Azul. O sistema de cores luminosas RGB (tamb\u00e9m designado por cor-luz) \u00e9 usado nos objetos que emitem luz como, por exemplo, os monitores de computador e televis\u00e3o, &hellip; <a href=\"https:\/\/www.mprinformatica.com.br\/blog\/2012\/07\/18\/o-que-e-rgb\/\" class=\"more-link\">Continuar lendo <span class=\"screen-reader-text\">O que \u00e9 RGB ?<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,11,13,17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/posts\/189"}],"collection":[{"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":0,"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/posts\/189\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mprinformatica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}